{"id":7168,"date":"2026-01-15T17:20:31","date_gmt":"2026-01-15T09:20:31","guid":{"rendered":"https:\/\/meettfit.com\/?p=7168"},"modified":"2026-01-17T16:41:58","modified_gmt":"2026-01-17T08:41:58","slug":"how-rubber-gym-flooring-performs-in-cold-climate-gyms","status":"publish","type":"post","link":"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/comment-les-revetements-de-sol-en-caoutchouc-se-comportent-ils-dans-les-salles-de-sport-en-climat-froid\/","title":{"rendered":"Performances des rev\u00eatements de sol en caoutchouc dans les salles de sport en climat froid"},"content":{"rendered":"<p><strong>R\u00e9ponse courte : Non, le froid n'ab\u00eemera pas votre rev\u00eatement de sol en caoutchouc. Toutefois, il entra\u00eenera un r\u00e9tr\u00e9cissement des tapis (cr\u00e9ant des interstices) et les rendra plus durs au toucher. Il peut \u00eatre utilis\u00e9 en toute s\u00e9curit\u00e9 dans des garages non chauff\u00e9s jusqu'\u00e0 -20\u00b0C, \u00e0 condition de ne pas l'installer ou le coller lorsqu'il est gel\u00e9. L'acclimatation est la cl\u00e9 du succ\u00e8s.<\/strong><\/p>\n<h3>TL;DR : La \"r\u00e9ponse rapide\" pour les propri\u00e9taires de salles de sport d\u00e9bord\u00e9s<\/h3>\n<p>If you are standing in your freezing garage right now wondering if you&#8217;ve made a mistake, here is the bottom line:<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Sc\u00e9nario<\/th>\n<th style=\"text-align: left;\">Survivra-t-il ?<\/th>\n<th style=\"text-align: left;\">Niveau de risque<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><strong>-10\u00b0C \u00e0 -20\u00b0C Garage non chauff\u00e9<\/strong><\/td>\n<td style=\"text-align: left;\"><strong>OUI<\/strong><\/td>\n<td style=\"text-align: left;\">\u2705 <strong>S\u00fbr.<\/strong> It will get hard, but won&#8217;t break.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Installation du froid (pas d'acclimatation)<\/strong><\/td>\n<td style=\"text-align: left;\"><strong>NON<\/strong><\/td>\n<td style=\"text-align: left;\">\u274c <strong>Risque \u00e9lev\u00e9.<\/strong> Il se d\u00e9formera et fera des bulles \u00e0 l'arriv\u00e9e de l'\u00e9t\u00e9.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Rouleaux de caoutchouc vulcanis\u00e9<\/strong><\/td>\n<td style=\"text-align: left;\"><strong>OUI<\/strong><\/td>\n<td style=\"text-align: left;\">\u2705 <strong>Meilleur choix.<\/strong> Moins poreux, il supporte mieux l'humidit\u00e9.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Caoutchouc bon march\u00e9 de faible densit\u00e9<\/strong><\/td>\n<td style=\"text-align: left;\"><strong>PEUT-\u00caTRE<\/strong><\/td>\n<td style=\"text-align: left;\">\u26a0\ufe0f <strong>Risque moyen.<\/strong> Peut se fragiliser\/se fissurer sous l'effet de fortes chutes.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Remplir les trous avec du mastic<\/strong><\/td>\n<td style=\"text-align: left;\"><strong>NON<\/strong><\/td>\n<td style=\"text-align: left;\">\u274c <strong>Don&#8217;t do it.<\/strong> Les lacunes se refermeront naturellement en \u00e9t\u00e9.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h2>Pourquoi les rev\u00eatements de sol en caoutchouc r\u00e9tr\u00e9cissent-ils et durcissent-ils en hiver ?<\/h2>\n<p><strong>Le caoutchouc est un polym\u00e8re qui r\u00e9agit \u00e0 la thermodynamique : le froid provoque une contraction lin\u00e9aire (lacunes) et augmente la densit\u00e9 (duret\u00e9). Il s'agit d'une r\u00e9action physique et non d'un d\u00e9faut. Un caoutchouc de haute qualit\u00e9 retrouvera son \u00e9tat d'origine lorsque les temp\u00e9ratures augmenteront, agissant comme un mat\u00e9riau \"vivant\" qui respire au fil des saisons.<\/strong><\/p>\n<h3>La science : Qu'arrive-t-il au caoutchouc par temps de gel ?<\/h3>\n<p>En tant qu'ing\u00e9nieur charg\u00e9 du contr\u00f4le de la qualit\u00e9, je re\u00e7ois souvent en janvier des appels de propri\u00e9taires de salles de sport paniqu\u00e9s qui me demandent : \"Pourquoi mon sol r\u00e9tr\u00e9cit-il ?\". Pour vous rassurer, il faut se pencher sur la science des mat\u00e9riaux. Le caoutchouc ob\u00e9it \u00e0 la <em>Coefficient de dilatation thermique lin\u00e9aire<\/em>. Lorsque la temp\u00e9rature ambiante baisse, les cha\u00eenes de polym\u00e8res se resserrent pour conserver l'\u00e9nergie.<\/p>\n<p>Concr\u00e8tement, un rev\u00eatement de sol en caoutchouc de 20 pieds peut se r\u00e9tr\u00e9cir d'environ 1\/4 \u00e0 1\/2 pouce lorsque la temp\u00e9rature passe de 21\u00b0C \u00e0 -1\u00b0C. C'est la raison pour laquelle des espaces g\u00eanants apparaissent soudainement entre vos tapis qui \u00e9taient auparavant bien serr\u00e9s. Ce n'est pas que le produit soit \"d\u00e9fectueux\" ou \"bon march\u00e9\" ; c'est simplement la physique qui fait son \u0153uvre.<\/p>\n<p>Deuxi\u00e8mement, nous observons un changement dans <strong>Durom\u00e8tre (duret\u00e9)<\/strong>. Le caoutchouc froid devient plus dense. Si vous utilisez un tapis en caoutchouc standard de Shore A 65, il peut sembler de Shore A 75 ou 80 dans des conditions de gel. Cela signifie que le sol devient moins souple. Alors que le caoutchouc vulcanis\u00e9 de haute qualit\u00e9 conserve suffisamment d'\u00e9lasticit\u00e9 pour r\u00e9sister \u00e0 la fissuration, les miettes de caoutchouc coll\u00e9es de qualit\u00e9 inf\u00e9rieure (souvent maintenues par des liants en polyur\u00e9thane bon march\u00e9) peuvent devenir cassantes. En cas de contrainte extr\u00eame, comme la chute d'un halt\u00e8re de 200 livres, le caoutchouc de qualit\u00e9 inf\u00e9rieure \u00e0 l'\u00e9tat congel\u00e9 risque davantage de se micro-fracturer parce que le liant perd sa flexibilit\u00e9.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-6-2.jpg&quot;\" alt=\"Comparaison des \u00e9carts de retrait des rev\u00eatements de sol en caoutchouc\" \/><\/p>\n<p>Now that we know the &quot;why,&quot; let&#8217;s look at the specific problems you will face and how to distinguish normal behavior from actual failure.<\/p>\n<h2>Quels sont les v\u00e9ritables \"points douloureux\" auxquels vous serez confront\u00e9s cet hiver ?<\/h2>\n<p><strong>Les trois principaux probl\u00e8mes sont le \"Gapping\" (les tapis s'\u00e9cartent les uns des autres), le \"Curling\" (les bords se soul\u00e8vent en raison d'une chaleur in\u00e9gale) et la \"Sweating Slab\" (condensation pi\u00e9g\u00e9e sous le tapis). Il s'agit de probl\u00e8mes de nuisance g\u00e9rables et non de d\u00e9faillances permanentes, \u00e0 condition de g\u00e9rer correctement l'humidit\u00e9.<\/strong><\/p>\n<h3>Principaux d\u00e9fis et points sensibles dans les climats froids<\/h3>\n<p>Au cours de mes ann\u00e9es d'inspection des am\u00e9nagements de salles de sport dans les climats nordiques, j'ai cat\u00e9goris\u00e9 les trois principaux modes de d\u00e9faillance qui se produisent en hiver. Comprendre ces modes vous aidera \u00e0 diagnostiquer si votre sol est d\u00e9faillant ou s'il r\u00e9agit normalement.<\/p>\n<p><strong>1. Le ph\u00e9nom\u00e8ne du \"Gapping<\/strong><br \/>\nC'est la plainte la plus fr\u00e9quente. Vous avez bien install\u00e9 vos tapis en septembre, mais en d\u00e9cembre, ils ressemblent \u00e0 un puzzle s\u00e9par\u00e9. Il s'agit d'un r\u00e9tr\u00e9cissement lin\u00e9aire. La salet\u00e9, la craie et les d\u00e9bris sont in\u00e9vitablement pi\u00e9g\u00e9s dans ces interstices. <em>Conseil de pro : Ne remplissez pas ces espaces avec du mastic permanent !<\/em> Si vous le faites, lorsque l'\u00e9t\u00e9 arrivera, les tapis se dilateront et n'auront nulle part o\u00f9 aller, ce qui les fera se d\u00e9former vers le haut.<\/p>\n<p><strong>2. Bordures boucl\u00e9es<\/strong><br \/>\nIl s'agit d'un probl\u00e8me plus subtil caus\u00e9 par une dynamique thermique in\u00e9gale. Si votre dalle de b\u00e9ton est extr\u00eamement froide (temp\u00e9rature du sol) mais que vous r\u00e9chauffez rapidement l'air de la pi\u00e8ce \u00e0 l'aide d'un chauffage d'appoint, la surface sup\u00e9rieure du caoutchouc se dilate tandis que la surface inf\u00e9rieure reste contract\u00e9e. Cette contrainte entra\u00eene une courbure des coins ou des bords vers le haut, ce qui cr\u00e9e un risque important de tr\u00e9buchement.<\/p>\n<p><strong>3. La \"dalle suintante\"<\/strong><br \/>\nC'est le probl\u00e8me le plus dangereux pour la durabilit\u00e9 \u00e0 long terme. Lorsque vous chauffez un gymnase de garage froid, l'air chaud contient de l'humidit\u00e9. Lorsque cet air touche le caoutchouc froid ou la dalle de b\u00e9ton froide qui se trouve en dessous, il se condense. Il m'est arriv\u00e9 d'arracher des tapis au printemps pour d\u00e9couvrir des moisissures noires qui se d\u00e9veloppaient en dessous parce que l'humidit\u00e9 avait \u00e9t\u00e9 pi\u00e9g\u00e9e entre le caoutchouc et le b\u00e9ton pendant tout l'hiver. Cela d\u00e9grade la qualit\u00e9 de l'air de votre salle de sport et peut lentement d\u00e9composer les liants des tapis en caoutchouc recycl\u00e9.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-5-2.jpg&quot;\" alt=\"Condensation de l&#039;humidit\u00e9 sous les tapis en caoutchouc\" \/><\/p>\n<p>Les changements physiques sont g\u00eanants, mais le v\u00e9ritable d\u00e9sastre se produit souvent avant m\u00eame l'ouverture du gymnase, pendant la phase d'installation.<\/p>\n<h2>Peut-on poser un rev\u00eatement de sol en caoutchouc dans une pi\u00e8ce glaciale ?<\/h2>\n<p><strong>NON, sauf si vous l'acclimatez. Vous devez laisser le caoutchouc reposer dans la pi\u00e8ce pendant 48 heures avant de le d\u00e9couper. Si vous d\u00e9coupez du caoutchouc froid pour l'adapter \u00e0 un mur, il se dilatera et se d\u00e9formera lorsque la pi\u00e8ce se r\u00e9chauffera. \u00c9vitez les colles \u00e0 base d'eau, car elles g\u00e8leront et ne fonctionneront pas.<\/strong><\/p>\n<h3>Cauchemars d'installation : La \"r\u00e8gle d'or\" de l'installation hivernale<\/h3>\n<p>En tant qu'ing\u00e9nieur charg\u00e9 du contr\u00f4le de la qualit\u00e9, je ne saurais trop insister sur ce point : <strong>L'acclimatation n'est pas facultative.<\/strong> J'ai vu d'innombrables installations bricol\u00e9es \u00e9chouer parce que le propri\u00e9taire avait re\u00e7u une livraison de rouleaux de caoutchouc froid, les avait d\u00e9roul\u00e9s imm\u00e9diatement, les avait coup\u00e9s pour les adapter aux murs et les avait coll\u00e9s.<\/p>\n<p>Voici la r\u00e9alit\u00e9 technique : Si vous coupez un rouleau de caoutchouc \u00e0 une temp\u00e9rature de -1\u00b0C (30\u00b0F), il est dans son \u00e9tat le plus contract\u00e9. Lorsque le printemps arrive et que la temp\u00e9rature ambiante atteint 21\u00b0C (70\u00b0F), ce rouleau de caoutchouc est dans son \u00e9tat le plus contract\u00e9. <em>volont\u00e9<\/em> expand. Since you cut it to fit perfectly against the wall, it has nowhere to go. The result is buckling or &quot;bubbling&quot; in the middle of the room. &#8230;You must unroll the rubber and let it sit in the room for at least 48 hours to reach an equilibrium temperature before you make a single cut. (For a complete technical checklist beyond climate concerns, see our <a href=\"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/que-faut-il-savoir-avant-de-choisir-et-dinstaller-un-revetement-de-sol-en-caoutchouc-pour-une-salle-de-sport\/\">Que faut-il savoir avant de choisir et de poser un sol de gymnastique en caoutchouc ?<\/a>)<\/p>\n<p>En outre, le choix de l'adh\u00e9sif est essentiel. Les adh\u00e9sifs autocollants standard, acryliques ou \u00e0 base d'eau, contiennent de l'eau. Dans une pi\u00e8ce non chauff\u00e9e, l'eau contenue dans la colle peut geler avant que l'adh\u00e9sif ne durcisse, d\u00e9truisant ainsi la liaison. Si vous devez coller dans le froid, vous avez besoin d'un adh\u00e9sif \u00e0 base d'eau. <strong>Adh\u00e9sif en polyur\u00e9thane (PU)<\/strong>. Le PU durcit par r\u00e9action \u00e0 l'humidit\u00e9, et non par \u00e9vaporation, et est g\u00e9n\u00e9ralement plus stable \u00e0 basse temp\u00e9rature. Cependant, pour la plupart des salles de sport en climat froid, je recommande d'\u00e9viter compl\u00e8tement la colle et d'utiliser du ruban adh\u00e9sif double face ou une pose \u00e0 sec pour permettre au sol de \"flotter\".<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-2-2.jpg&quot;\" alt=\"Acclimatation des rouleaux de caoutchouc dans le garage\" \/><\/p>\n<p>Once installed, does the cold affect your actual lifting? Let&#8217;s look at performance.<\/p>\n<h2>Est-il dangereux de soulever des charges sur du caoutchouc gel\u00e9 ?<\/h2>\n<p><strong>En g\u00e9n\u00e9ral, non. Le coefficient de frottement reste \u00e9lev\u00e9 (antid\u00e9rapant), sauf en cas de formation de givre. L'absorption des chocs est l\u00e9g\u00e8rement r\u00e9duite, mais la stabilit\u00e9 pour les charges lourdes comme les squats est en fait am\u00e9lior\u00e9e parce que le caoutchouc est plus ferme et moins compressible.<\/strong><\/p>\n<h3>Performance et s\u00e9curit\u00e9 : S'entra\u00eener dans le froid<\/h3>\n<p>Du point de vue des performances, le caoutchouc froid offre un compromis. Nous v\u00e9rifions le coefficient de frottement (COF) dans nos laboratoires et le caoutchouc sec conserve g\u00e9n\u00e9ralement son adh\u00e9rence m\u00eame lorsqu'il g\u00e8le. Cependant, le danger provient de la \"transpiration\" mentionn\u00e9e plus haut. Une fine couche de givre ou de condensation sur le caoutchouc le transforme en patinoire. Vous devez v\u00e9rifier que la surface est s\u00e8che avant d'effectuer des mouvements dynamiques tels que des box jumps.<\/p>\n<p>En ce qui concerne <strong>Absorption des chocs<\/strong>La physique du mat\u00e9riau change. Comme le caoutchouc durcit (augmentation du durom\u00e8tre), le \"rebond\" ou la restitution d'\u00e9nergie est plus faible.<\/p>\n<ul>\n<li><strong>Pour l'halt\u00e9rophilie olympique :<\/strong> La barre peut ne pas rebondir aussi haut lorsqu'elle est l\u00e2ch\u00e9e. La signature acoustique changera \u00e9galement : le \"bruit sourd\" sera plus net et plus fort.<\/li>\n<li><strong>Pour le Powerlifting :<\/strong> Il s'agit en fait d'un avantage. Lorsque vous faites du squat ou du deadlifting, vous avez besoin d'un sol qui ne soit pas compressible. Le caoutchouc froid et dur fournit une plateforme incroyablement stable, r\u00e9duisant la fuite d'\u00e9nergie que vous pourriez ressentir sur des tapis plus doux et plus chauds.<\/li>\n<\/ul>\n<p>Bien que le caoutchouc prot\u00e8ge efficacement votre b\u00e9ton dans le froid, nous devons nous assurer que nous utilisons le bon mat\u00e9riau. <em>type<\/em> de caoutchouc au d\u00e9part.<\/p>\n<h2>Comment choisir le bon rev\u00eatement de sol pour les climats froids ?<\/h2>\n<p><strong>Pr\u00e9f\u00e9rez les rouleaux de caoutchouc vulcanis\u00e9 aux dalles \u00e0 embo\u00eetement. Le caoutchouc vulcanis\u00e9 est non poreux (imperm\u00e9able) et les rouleaux pr\u00e9sentent moins de joints que les dalles, ce qui r\u00e9duit le nombre de fentes qui s'ouvriront lorsque la temp\u00e9rature baissera.<\/strong><\/p>\n<h3>Meilleures pratiques : Comment prot\u00e9ger le sol de votre salle de sport contre l'hiver<\/h3>\n<p>Si vous concevez une salle de sport pour une r\u00e9gion comme le Minnesota, l'Alberta ou l'Europe du Nord, votre strat\u00e9gie de s\u00e9lection des produits doit \u00eatre diff\u00e9rente de celle d'une salle de sport situ\u00e9e en Floride.<\/p>\n<p><strong>1. Vulcanisation et recyclage des miettes<\/strong><br \/>\nJe recommande vivement <strong>Caoutchouc vulcanis\u00e9<\/strong> pour les climats extr\u00eames. Le caoutchouc recycl\u00e9 est poreux ; il est constitu\u00e9 de granul\u00e9s coll\u00e9s les uns aux autres. L'eau peut s'infiltrer dans les pores, geler et se dilater, ce qui risque de rompre les liens apr\u00e8s des ann\u00e9es de cycles. Le caoutchouc vulcanis\u00e9 est non poreux et chimiquement r\u00e9ticul\u00e9, ce qui le rend imperm\u00e9able \u00e0 l'eau et aux cycles de gel et de d\u00e9gel.<\/p>\n<ol start=\"2\">\n<li>Rouleaux et tuiles<br \/>\nUtiliser des rouleaux. Les tuiles \u00e0 embo\u00eetement s'appuient sur des languettes pour se maintenir ensemble. Lorsque les dalles r\u00e9tr\u00e9cissent sous l'effet du froid, les languettes se d\u00e9tachent et l'embo\u00eetement peut se rompre. Si vous souhaitez en savoir plus sur les raisons pour lesquelles les rouleaux sont le meilleur choix pour les grandes surfaces n\u00e9cessitant peu d'entretien, lisez notre guide sur les dalles \u00e0 embo\u00eetement. <a href=\"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/quest-ce-quun-revetement-de-sol-en-caoutchouc-pour-gymnase\/\">Qu'est-ce qu'un rev\u00eatement de sol en caoutchouc ?<\/a> Les rouleaux ont moins de coutures et sont suffisamment lourds (surtout 8 mm ou 10 mm d'\u00e9paisseur) pour se mettre \u00e0 plat sous leur propre poids.<\/li>\n<\/ol>\n<p><strong>3. La m\u00e9thode \"flottante\" et la gestion des \u00e9carts<\/strong><br \/>\nNe collez pas le sol. Utilisez une installation \"flottante\" en collant les joints des rouleaux \u00e0 l'aide d'une bande de moquette tr\u00e8s r\u00e9sistante ou en utilisant des chevilles de raccord (pour les dalles).<\/p>\n<ul>\n<li><strong>Gestion des \u00e9carts :<\/strong> Appliquez du ruban adh\u00e9sif noir sur le <em>dessous<\/em> des tapis le long des coutures. Cela permet de maintenir les tapis ensemble tout en permettant \u00e0 l'ensemble du plancher de bouger l\u00e9g\u00e8rement.<\/li>\n<li><strong>Joints de dilatation :<\/strong> Laissez un espace l\u00e9g\u00e8rement plus grand (1\/4 de pouce) sur les murs que vous le feriez en \u00e9t\u00e9. Cela permet de tenir compte de la dilatation qui se produira lorsque le temps se r\u00e9chauffera.<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-4-2.jpg&quot;\" alt=\"Rouleaux vulcanis\u00e9s ou tuiles \u00e0 embo\u00eetement\" \/><\/p>\n<p>Finally, let&#8217;s address maintenance, because cleaning in winter is tricky.<\/p>\n<h2>Comment nettoyer le sol de ma salle de sport sans en faire une patinoire ?<\/h2>\n<p><strong>\u00c9vitez de passer la serpilli\u00e8re humide ; utilisez une serpilli\u00e8re en microfibres humide pour \u00e9viter la formation de glace. Si vous utilisez des radiateurs d'appoint, ne les placez jamais directement sur la surface en caoutchouc, car la chaleur localis\u00e9e peut provoquer une d\u00e9formation ou une fonte permanente.<\/strong><\/p>\n<h3>Conseils d'entretien par temps froid<\/h3>\n<p>L'entretien dans un environnement froid n\u00e9cessite une approche diff\u00e9rente de celle du nettoyage commercial standard.<\/p>\n<p><strong>Strat\u00e9gie de nettoyage<\/strong><br \/>\nN'utilisez plus de seau et de serpilli\u00e8re pour \u00e9vacuer l'eau exc\u00e9dentaire. Dans un garage non chauff\u00e9, cette eau ne s'\u00e9vaporera pas rapidement. Elle restera sur la surface, s'infiltrera dans les joints et g\u00e8lera.<\/p>\n<ul>\n<li><strong>Action :<\/strong> Utilisez une serpilli\u00e8re en microfibres \u00e0 peine humide (vaporisez-la avec un nettoyant \u00e0 pH neutre). L'humidit\u00e9 doit s\u00e9cher presque instantan\u00e9ment. Si vous avez des taches de sel dues aux bottes d'hiver, utilisez un nettoyant sp\u00e9cifique neutralisant le sel, mais aspirez imm\u00e9diatement le liquide \u00e0 l'aide d'un aspirateur \u00e0 eau.<\/li>\n<\/ul>\n<p><strong>S\u00e9curit\u00e9 du chauffage<\/strong><br \/>\nJ'ai analys\u00e9 des \u00e9chantillons de caoutchouc d\u00e9fectueux qui avaient \"fondu\". Cela se produit presque toujours parce que l'utilisateur a plac\u00e9 un radiateur \u00e0 haut rendement ou un radiateur infrarouge directement sur le tapis.<\/p>\n<ul>\n<li><strong>La science :<\/strong> Le caoutchouc est un isolant. Si vous envoyez de la chaleur \u00e0 un endroit, la chaleur reste pi\u00e9g\u00e9e dans le caoutchouc et ne peut pas se dissiper dans le b\u00e9ton en dessous. Cette accumulation de chaleur localis\u00e9e peut d\u00e9grader le polym\u00e8re.<\/li>\n<li><strong>Recommandation :<\/strong> Placez toujours les appareils de chauffage sur un tabouret ou un bloc ininflammable, ou utilisez des appareils de chauffage \u00e0 ventilateur qui font circuler l'air plut\u00f4t que de chauffer directement le sol.<\/li>\n<\/ul>\n<p>Let&#8217;s wrap up with the specific questions I get asked every single winter.<\/p>\n<h2>FAQ : Les r\u00e9ponses \u00e0 vos questions sur la panique<\/h2>\n<p><strong>Yes, you can leave mats outside. No, don&#8217;t fill the gaps with caulk. The rubber is fine, it&#8217;s just reacting to physics. Keep it dry, keep it clean, and wait for summer for the gaps to close.<\/strong><\/p>\n<h3>FAQ (Foire aux questions)<\/h3>\n<p><strong>Puis-je laisser les tapis en caoutchouc \u00e0 l'ext\u00e9rieur dans la neige ?<\/strong><br \/>\nOui. Les caoutchoucs SBR (caoutchouc styr\u00e8ne-butadi\u00e8ne) et EPDM de haute qualit\u00e9 sont chimiquement stables \u00e0 des temp\u00e9ratures de cong\u00e9lation. Le froid n'endommage pas la structure mol\u00e9culaire. Toutefois, il faut savoir que la lumi\u00e8re du soleil (rayons UV) cause plus de d\u00e9g\u00e2ts que la neige. Si vous les stockez \u00e0 l'ext\u00e9rieur, recouvrez-les d'une b\u00e2che pour \u00e9viter la d\u00e9gradation par les UV.<\/p>\n<p><strong>Mon rev\u00eatement de sol en caoutchouc se fissurera-t-il si j'y d\u00e9pose un poids par -10\u00b0C ?<\/strong><br \/>\nIl est tr\u00e8s peu probable que cela se produise si vous utilisez un rev\u00eatement de sol de gymnase appropri\u00e9 (\u00e9paisseur de 8 mm ou plus). Nous testons la r\u00e9sistance aux chocs du caoutchouc. Bien que le caoutchouc soit plus dur \u00e0 -10\u00b0C, il poss\u00e8de encore suffisamment de propri\u00e9t\u00e9s d'\u00e9longation pour absorber le choc. Toutefois, si vous utilisez un caoutchouc tr\u00e8s fin (3 \u00e0 4 mm) ou de faible densit\u00e9, le risque augmente.<\/p>\n<p><strong>Comment combler les lacunes apparues cet hiver ?<\/strong><br \/>\nNe les remplissez pas avec du mastic ou du calfeutrage ! Comme nous l'avons mentionn\u00e9, il s'agit d'une contraction thermique. Si vous comblez les interstices maintenant, l'\u00e9t\u00e9 venu, les nattes se dilateront et le mastic sera repouss\u00e9 ou les nattes se d\u00e9formeront. La meilleure solution est de recoller les tapis et d'appliquer du ruban adh\u00e9sif sur la face inf\u00e9rieure, ou d'accepter simplement que de l\u00e9g\u00e8res fentes soient un comportement saisonnier du mat\u00e9riau.<\/p>\n<p><strong>Les rev\u00eatements de sol en caoutchouc isolent-ils la pi\u00e8ce ?<\/strong><br \/>\nRubber has a low R-value (insulation value), so it doesn&#8217;t &quot;insulate&quot; like fiberglass in a wall. However, it acts as an excellent <strong>Rupture thermique<\/strong>. Il emp\u00eache la conduction de la chaleur corporelle dans la dalle de b\u00e9ton gel\u00e9e. En se tenant debout sur du caoutchouc, on a nettement plus chaud qu'en se tenant debout sur du b\u00e9ton nu, car on cesse de perdre de la chaleur par les pieds.<\/p>\n<h2>Conclusion<\/h2>\n<p>Don&#8217;t let the cold stop your training. Rubber flooring is resilient, tough, and perfectly capable of handling freezing temperatures if you respect its properties. Expect some shrinkage, avoid winter installation if possible (or acclimatize religiously), and keep moisture in check. Your floor will survive the winter just fine.<\/p>\n<hr \/>\n<p><strong>Vous ne savez toujours pas si votre installation actuelle peut supporter le froid ?<\/strong><br \/>\nYou don&#8217;t have to guess. <strong>Contactez notre \u00e9quipe d'ing\u00e9nieurs<\/strong>-Nous pouvons examiner les sp\u00e9cifications de votre garage ou de votre entrep\u00f4t et vous recommander l'\u00e9paisseur et la densit\u00e9 exactes dont vous avez besoin. Demandez un \"kit d'\u00e9chantillons pour climat froid\" gratuit pour tester le mat\u00e9riau vous-m\u00eame.<\/p>","protected":false},"excerpt":{"rendered":"<p>Short Answer: No, cold weather will not ruin your rubber flooring. However, it will cause the mats to shrink (creating gaps) and feel harder. It is safe to use in unheated garages down to -20\u00b0C, provided you do not install or glue it while it is frozen. Acclimatization is the key to success. TL;DR: The&#8230;<\/p>","protected":false},"author":4,"featured_media":7171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-7168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rubber-floor-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR<\/title>\n<meta name=\"description\" content=\"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/comment-les-revetements-de-sol-en-caoutchouc-se-comportent-ils-dans-les-salles-de-sport-en-climat-froid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR\" \/>\n<meta property=\"og:description\" content=\"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/comment-les-revetements-de-sol-en-caoutchouc-se-comportent-ils-dans-les-salles-de-sport-en-climat-froid\/\" \/>\n<meta property=\"og:site_name\" content=\"MF FLOOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100079773047357\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T09:20:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-17T08:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/\"},\"author\":{\"name\":\"Leo\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef\"},\"headline\":\"How Rubber Gym Flooring Performs in Cold Climate Gyms\",\"datePublished\":\"2026-01-15T09:20:31+00:00\",\"dateModified\":\"2026-01-17T08:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/\"},\"wordCount\":2355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/meettfit.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg\",\"articleSection\":[\"Resilient Flooring Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/\",\"url\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/\",\"name\":\"How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR\",\"isPartOf\":{\"@id\":\"https:\/\/meettfit.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg\",\"datePublished\":\"2026-01-15T09:20:31+00:00\",\"dateModified\":\"2026-01-17T08:41:58+00:00\",\"description\":\"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.\",\"breadcrumb\":{\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage\",\"url\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg\",\"contentUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg\",\"width\":800,\"height\":600,\"caption\":\"Rubber Gym Flooring (3)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/meettfit.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Rubber Gym Flooring Performs in Cold Climate Gyms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/meettfit.com\/#website\",\"url\":\"https:\/\/meettfit.com\/\",\"name\":\"MF FLOOR\",\"description\":\"fitness and sports floor China factory\",\"publisher\":{\"@id\":\"https:\/\/meettfit.com\/#organization\"},\"alternateName\":\"MF FLOOR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/meettfit.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/meettfit.com\/#organization\",\"name\":\"MF FLOOR\",\"alternateName\":\"MF FLOOR\",\"url\":\"https:\/\/meettfit.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png\",\"contentUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png\",\"width\":512,\"height\":512,\"caption\":\"MF FLOOR\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100079773047357\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef\",\"name\":\"Leo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g\",\"caption\":\"Leo\"},\"url\":\"https:\/\/meettfit.com\/fr\/author\/1659230944qq-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR","description":"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/comment-les-revetements-de-sol-en-caoutchouc-se-comportent-ils-dans-les-salles-de-sport-en-climat-froid\/","og_locale":"fr_FR","og_type":"article","og_title":"How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR","og_description":"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.","og_url":"https:\/\/meettfit.com\/fr\/blog-sur-les-sols-en-caoutchouc\/comment-les-revetements-de-sol-en-caoutchouc-se-comportent-ils-dans-les-salles-de-sport-en-climat-froid\/","og_site_name":"MF FLOOR","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100079773047357","article_published_time":"2026-01-15T09:20:31+00:00","article_modified_time":"2026-01-17T08:41:58+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg","type":"image\/jpeg"}],"author":"Leo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Leo","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#article","isPartOf":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/"},"author":{"name":"Leo","@id":"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef"},"headline":"How Rubber Gym Flooring Performs in Cold Climate Gyms","datePublished":"2026-01-15T09:20:31+00:00","dateModified":"2026-01-17T08:41:58+00:00","mainEntityOfPage":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/"},"wordCount":2355,"commentCount":0,"publisher":{"@id":"https:\/\/meettfit.com\/#organization"},"image":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage"},"thumbnailUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg","articleSection":["Resilient Flooring Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/","url":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/","name":"How Rubber Gym Flooring Performs in Cold Climate Gyms - MF FLOOR","isPartOf":{"@id":"https:\/\/meettfit.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage"},"image":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage"},"thumbnailUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg","datePublished":"2026-01-15T09:20:31+00:00","dateModified":"2026-01-17T08:41:58+00:00","description":"Planning a gym in cold climates? Learn why vulcanized rubber rolls outperform tiles in freezing temperatures and how to manage winter gaps and moisture.","breadcrumb":{"@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#primaryimage","url":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg","contentUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/01\/Rubber-Gym-Flooring-3-2.jpg","width":800,"height":600,"caption":"Rubber Gym Flooring (3)"},{"@type":"BreadcrumbList","@id":"https:\/\/meettfit.com\/rubber-floor-blog\/how-rubber-gym-flooring-performs-in-cold-climate-gyms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/meettfit.com\/"},{"@type":"ListItem","position":2,"name":"How Rubber Gym Flooring Performs in Cold Climate Gyms"}]},{"@type":"WebSite","@id":"https:\/\/meettfit.com\/#website","url":"https:\/\/meettfit.com\/","name":"MF FLOOR","description":"fitness and sports floor China factory","publisher":{"@id":"https:\/\/meettfit.com\/#organization"},"alternateName":"MF FLOOR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meettfit.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/meettfit.com\/#organization","name":"MF FLOOR","alternateName":"MF FLOOR","url":"https:\/\/meettfit.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meettfit.com\/#\/schema\/logo\/image\/","url":"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png","contentUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png","width":512,"height":512,"caption":"MF FLOOR"},"image":{"@id":"https:\/\/meettfit.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100079773047357"]},{"@type":"Person","@id":"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef","name":"Leo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meettfit.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g","caption":"Leo"},"url":"https:\/\/meettfit.com\/fr\/author\/1659230944qq-com\/"}]}},"_links":{"self":[{"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/posts\/7168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/comments?post=7168"}],"version-history":[{"count":1,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/posts\/7168\/revisions"}],"predecessor-version":[{"id":7193,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/posts\/7168\/revisions\/7193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/media\/7171"}],"wp:attachment":[{"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/media?parent=7168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/categories?post=7168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meettfit.com\/fr\/wp-json\/wp\/v2\/tags?post=7168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}