{"id":8329,"date":"2026-04-21T17:00:45","date_gmt":"2026-04-21T09:00:45","guid":{"rendered":"https:\/\/meettfit.com\/?p=8329"},"modified":"2026-04-22T11:07:39","modified_gmt":"2026-04-22T03:07:39","slug":"what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns","status":"publish","type":"post","link":"https:\/\/meettfit.com\/de\/akustische-unterlage\/welche-dehnungsfuge-braucht-ein-gummibodenbelag-an-wanden-und-saulen\/","title":{"rendered":"Welche Dehnungsfuge braucht ein Gummibodenbelag an W\u00e4nden und S\u00e4ulen?"},"content":{"rendered":"<p>Standard-Gummibodenbel\u00e4ge erfordern eine Dehnungsfuge von <strong>1\/4 Zoll bis 3\/8 Zoll (6 mm bis 10 mm)<\/strong> an allen W\u00e4nden und festen S\u00e4ulen. Dieser Raum erm\u00f6glicht es dem Material, sich aufgrund von Temperatur- und Feuchtigkeitsschwankungen auf nat\u00fcrliche Weise auszudehnen und zusammenzuziehen, ohne dass es zu Beulen oder Nahtausf\u00e4llen kommt.<\/p>\n<p>Ich habe viele Jahre auf Baustellen verbracht und kann Ihnen sagen, dass Gummi ein dynamisches Material ist. Auch wenn sich eine hochdichte Gummirolle fest und schwer anf\u00fchlt, reagiert sie auf ihre Umgebung wie ein lebendiges Wesen. Viele Bauunternehmer denken, dass sie den Gummi fest an die Wand dr\u00fccken k\u00f6nnen, um ein \"sauberes Aussehen\" zu erzielen, aber das ist ein gro\u00dfer Fehler. Wenn die Raumtemperatur ansteigt, dehnen sich die Gummimolek\u00fcle aus. Wenn kein Spalt vorhanden ist, kann der Druck nur nach oben gehen, was zu unsch\u00f6nen Blasen oder Wellen\" in der Mitte des Bodens Ihrer Sporthalle f\u00fchrt. Diese physikalische Realit\u00e4t gilt f\u00fcr recyceltes SBR und neues EPDM gleicherma\u00dfen. Wird dieser kleine Spalt ignoriert, f\u00fchrt dies oft zu einem v\u00f6lligen Versagen des Klebers, da die schiere Kraft des sich ausdehnenden Gummis st\u00e4rker ist als die meisten Klebstoffe.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-1-9.jpg&quot;\" alt=\"Gummibodenbelag Dehnungsfuge an der Wand mit Abstandshaltern\" \/><\/p>\n<p>Die richtige Planung f\u00fcr diese L\u00fccken ist der Unterschied zwischen einem Fu\u00dfboden, der zwanzig Jahre h\u00e4lt, und einem, der in zwei Monaten versagt.<\/p>\n<h2>Warum dehnt sich ein Gummibodenbelag aus und zieht sich zusammen?<\/h2>\n<p><strong>Die Hauptursache f\u00fcr die Bewegung ist die thermische Ausdehnung, bei der sich das Volumen des Gummis mit steigender Temperatur vergr\u00f6\u00dfert, und die mechanische Entspannung, bei der sich das Gummi \"ausdehnt\", nachdem es w\u00e4hrend der Herstellung und des Transports fest auf Rollen gewickelt wurde.<\/strong><\/p>\n<p>Das Verst\u00e4ndnis der Wissenschaft hinter dem Material hilft, Installationskatastrophen zu vermeiden. Gummi ist sehr empfindlich gegen\u00fcber der Umgebung. Obwohl er von Natur aus wasserbest\u00e4ndig ist, ist er nicht immun gegen hygroskopische Kr\u00e4fte. Wenn Ihr Unterboden eine hohe Wasserdampf-Emissionsrate (MVER) aufweist, kann dieser Druck die Dimensionsstabilit\u00e4t des Gummis und die Haftung des Klebstoffs beeintr\u00e4chtigen. Au\u00dferdem m\u00fcssen wir den \"Memory-Effekt\" ber\u00fccksichtigen. Wenn ich eine 8-mm-Gummirolle mit einer L\u00e4nge von 100 Fu\u00df abrolle, steht das Material seit Wochen unter Spannung. Es m\u00f6chte in seinen urspr\u00fcnglichen flachen Zustand zur\u00fcckkehren. Diese mechanische Entspannung kann bis zu 48 Stunden dauern.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Faktor<\/th>\n<th style=\"text-align: left;\">Auswirkungen auf Gummi<\/th>\n<th style=\"text-align: left;\">Empfohlene Ma\u00dfnahmen<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Temperaturerh\u00f6hung<\/td>\n<td style=\"text-align: left;\">Erweiterung<\/td>\n<td style=\"text-align: left;\">1\/4\" Abstand beibehalten<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Feuchtigkeit\/Feuchtigkeit<\/td>\n<td style=\"text-align: left;\">Instabilit\u00e4t des Systems<\/td>\n<td style=\"text-align: left;\">Dampfsperre verwenden<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Rollenspannung<\/td>\n<td style=\"text-align: left;\">Materialschrumpfung\/Kriechen<\/td>\n<td style=\"text-align: left;\">48 Stunden Akklimatisierung<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">UV-Belastung<\/td>\n<td style=\"text-align: left;\">Verschlechterung\/Expansion<\/td>\n<td style=\"text-align: left;\">Verwendung von UV-stabilisiertem EPDM<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>I once saw a project where the team installed the floor in a cold, unheated building in winter. Once the HVAC system was turned on and the room reached 75\u00b0F, the entire floor buckled because they didn&#8217;t account for the thermal expansion coefficient of the recycled SBR.<\/p>\n<p>Aus diesem Grund m\u00fcssen wir f\u00fcr jeden Quadratmeter der Anlage strenge Anforderungen erf\u00fcllen.<\/p>\n<h2>Was sind die endg\u00fcltigen Anforderungen an die Dehnungsfuge?<\/h2>\n<p><strong>F\u00fcr Standardr\u00e4ume ist ein Spalt von 1\/4 Zoll (6 mm) ausreichend, aber f\u00fcr gro\u00dfe gewerbliche R\u00e4ume \u00fcber 1.000 Quadratfu\u00df m\u00fcssen Sie den Spalt auf 3\/8 Zoll oder 1\/2 Zoll erh\u00f6hen, um die kumulative Materialbewegung aufzunehmen.<\/strong><\/p>\n<p>In my experience, the complexity increases when you deal with obstacles like support columns. While a straight wall is easy to manage, a column creates a focal point for stress. You need to maintain a perfect perimeter around every fixed object. If the floor hits a column, it can&#8217;t move past it, which creates a pressure point. I always use plastic spacers during the layout phase to ensure these gaps remain consistent throughout the entire room. If you are working in a massive warehouse or a professional crossfit center, the &quot;creep&quot; of the material over 50 linear feet can be significant.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Bereich Typ<\/th>\n<th style=\"text-align: left;\">Gr\u00f6\u00dfe des Zimmers<\/th>\n<th style=\"text-align: left;\">Erforderliche L\u00fccke<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Fitnessstudio f\u00fcr Privatpersonen<\/td>\n<td style=\"text-align: left;\">Unter 500 sq. ft.<\/td>\n<td style=\"text-align: left;\">1\/4\" (6mm)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Standard Kommerziell<\/td>\n<td style=\"text-align: left;\">500 &#8211; 1,500 sq. ft.<\/td>\n<td style=\"text-align: left;\">3\/8\" (10mm)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Gro\u00dfe Einrichtung<\/td>\n<td style=\"text-align: left;\">\u00dcber 1.500 Quadratmeter.<\/td>\n<td style=\"text-align: left;\">1\/2\" (13mm)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Pr\u00e4zision an der Peripherie<\/h3>\n<p>Using spacers is not just for tile; it is vital for rubber. Without them, the weight of the rubber rolls can shift during the gluing process, closing your gap before the adhesive sets. I always tell my crew that a uniform gap is easier to cover with trim later. If the gap varies from 1\/8&quot; to 1\/2&quot;, your baseboard won&#8217;t hide the mistakes.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-5-9.jpg&quot;\" alt=\"Messung der Dehnungsfuge um die S\u00e4ulen\" \/><\/p>\n<p>Der richtige Abstand ist nur die halbe Miete; man muss auch wissen, wie man das Material f\u00fcr diese Zwischenr\u00e4ume zuschneidet.<\/p>\n<h2>Wie messen und schneiden Sie um Hindernisse herum?<\/h2>\n<p><strong>Die effektivste Methode ist es, den Gummi 48 Stunden lang akklimatisieren zu lassen und dann einen \"Radialschnitt\" f\u00fcr S\u00e4ulen und einen \"Trim-to-Fit\"-Ansatz f\u00fcr W\u00e4nde mit einem professionellen Universalmesser und einem T-Quadrat zu verwenden.<\/strong><\/p>\n<p>Acclimatization is the most skipped step in the industry, and it is the most important. I require all my materials to sit in the installation space, unrolled if possible, for at least two days. This allows the rubber to reach thermal equilibrium with the room. For walls, I use the &quot;Oversize and Trim&quot; technique. I lay the roll with an extra inch climbing up the wall, let it settle, and then use a sharp blade to trim it back to the 1\/4&quot; mark. For columns, I create a paper template first. I cut the paper to fit the column perfectly, then transfer that shape to the rubber, making sure to add the necessary expansion gap to the template&#8217;s dimensions.<\/p>\n<h3>Werkzeuge und Techniken f\u00fcr saubere Schnitte<\/h3>\n<p>Eine stumpfe Klinge ist Ihr schlimmster Feind. Ich wechsele die Klingen meines Universalmessers alle 50 Fu\u00df, wenn ich schneide. Bei S\u00e4ulen besteht der \"Radialschnitt\" darin, einen geraden Schnitt von der n\u00e4chstgelegenen Naht zur Mitte der S\u00e4ule zu machen und dann die kreisf\u00f6rmige \u00d6ffnung zu schneiden. So kann sich das Gummi ohne Spannung um das Hindernis wickeln.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Name des Werkzeugs<\/th>\n<th style=\"text-align: left;\">Anwendungsfall<\/th>\n<th style=\"text-align: left;\">Nutzen Sie<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Hochwertiges Universalmesser<\/td>\n<td style=\"text-align: left;\">Beschneiden der Perimeter<\/td>\n<td style=\"text-align: left;\">Saubere, entgratete Kanten<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Stahl T-Quadrat<\/td>\n<td style=\"text-align: left;\">Gerade Wandschnitte<\/td>\n<td style=\"text-align: left;\">Gew\u00e4hrleistet 90-Grad-Genauigkeit<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Kreidelinie<\/td>\n<td style=\"text-align: left;\">Langlaufmarkierung<\/td>\n<td style=\"text-align: left;\">Beh\u00e4lt die Ausrichtung \u00fcber die Entfernung bei<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Kunststoff-Abstandshalter<\/td>\n<td style=\"text-align: left;\">Wartung der L\u00fccken<\/td>\n<td style=\"text-align: left;\">Garantierter Erweiterungsspielraum<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Sobald die Fugen richtig geschnitten sind, geht es darum, die Installation professionell aussehen zu lassen.<\/p>\n<h2>Welche L\u00f6sungen gibt es f\u00fcr die Bew\u00e4ltigung der L\u00fccke?<\/h2>\n<p><strong>Sie k\u00f6nnen Dehnungsfugen mit 4-Zoll-Gummiunterlegern, Aluminium\u00fcbergangsleisten an T\u00fcr\u00f6ffnungen oder flexiblem Silikondichtstoff f\u00fcr Bereiche, in denen Feuchtigkeitsschutz um S\u00e4ulen erforderlich ist, verbergen.<\/strong><\/p>\n<p>Niemand m\u00f6chte ein 1\/4-Zoll-Loch an der Kante seiner sch\u00f6nen neuen Turnhalle sehen. Im gewerblichen Bereich verwenden wir fast immer einen 4-Zoll-Gummisockel. Diese Verkleidung ist flexibel genug, um leichten Kurven in der Wand zu folgen und gleichzeitig die Dehnungsfuge vollst\u00e4ndig zu verbergen. In privaten Fitnessstudios bevorzugen manche Kunden eine normale Schuhleiste aus Holz. Sie m\u00fcssen jedoch sicherstellen, dass die Leiste an die Wand und nicht an den Boden genagelt wird, damit sich der Gummi unter ihr bewegen kann. Um S\u00e4ulen in Bereichen, die mit Wasser in Ber\u00fchrung kommen k\u00f6nnten - wie in der N\u00e4he von Wasserspendern - verwende ich ein farblich abgestimmtes, hochflexibles Silikondichtmittel. Diese f\u00fcllt die L\u00fccke, um zu verhindern, dass Wasser in den Unterboden eindringt, bleibt aber weich genug, um sich zusammenzudr\u00fccken, wenn sich das Gummi ausdehnt.<\/p>\n<h3>Fertigstellung der Details<\/h3>\n<p>\u00dcbergangsstreifen sind eine weitere wichtige Komponente. Wenn der Gummi auf ein anderes Material wie Teppich oder Fliesen trifft, muss die Dehnungsfuge innerhalb des \u00dcbergangskanals bestehen bleiben. Ich bevorzuge flache Reduzierst\u00fccke aus Aluminium, weil sie eine \"schwimmende\" Kante f\u00fcr den Gummi bieten. So kann der Boden atmen und bietet gleichzeitig eine sichere, stolperfreie Kante f\u00fcr die Mitglieder des Fitnessstudios.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Finish-Option<\/th>\n<th style=\"text-align: left;\">Am besten f\u00fcr<\/th>\n<th style=\"text-align: left;\">\u00c4sthetik<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Gummi-Voutenboden<\/td>\n<td style=\"text-align: left;\">Kommerzielle Fitnessstudios<\/td>\n<td style=\"text-align: left;\">Industriell\/Professionell<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Silikondichtmittel<\/td>\n<td style=\"text-align: left;\">Nassbereiche\/S\u00e4ulen<\/td>\n<td style=\"text-align: left;\">Nahtlos\/Sauber<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\u00dcbergangsstreifen<\/td>\n<td style=\"text-align: left;\">T\u00fcr\u00f6ffnungen<\/td>\n<td style=\"text-align: left;\">Sicher\/Funktional<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Holz-Schuhform<\/td>\n<td style=\"text-align: left;\">Heim-Turnhallen<\/td>\n<td style=\"text-align: left;\">Wohnen\/High-End<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-3-9.jpg&quot;\" alt=\"Einbau der Gummibodenplatte \u00fcber der Dehnungsfuge\" \/><\/p>\n<p>Selbst bei der besten Ausf\u00fchrung k\u00f6nnen bestimmte h\u00e4ufige Fehler das Projekt ruinieren.<\/p>\n<h2>Was sind h\u00e4ufige Fehler und wie lassen sie sich vermeiden?<\/h2>\n<p><strong>Zu den h\u00e4ufigsten Fehlern geh\u00f6ren ein zu festes Verkeilen\" des Gummis, die Verlegung bei extremen Temperaturen und die Nichtber\u00fccksichtigung, dass verschiedene Klebemethoden die Materialbewegung einschr\u00e4nken.<\/strong><\/p>\n<p>I often see DIY installers &quot;wedge&quot; the last piece of rubber into the gap to make it look tight. This is a disaster waiting to happen. As soon as the sun hits that floor through a window, the rubber expands, hits the wall, and the entire floor lifts off the ground. This is called &quot;bubbling.&quot; Another mistake is ignoring the HVAC status. If you install the floor before the building&#8217;s climate control is active, the expansion rates will be unpredictable. Finally, consider your adhesive. A &quot;Full Spread&quot; glue-down installation restricts movement more than &quot;Loose Lay&quot; or &quot;Tape&quot; methods. If you are gluing the floor down, the expansion gap is even more critical because the stress is transferred directly to the adhesive bond.<\/p>\n<h3>Professionelle Fehlersuche<\/h3>\n<p>Wenn Sie sehen, dass sich Ihr Boden an den N\u00e4hten zu w\u00f6lben beginnt, bedeutet dies in der Regel, dass die Fugen am Rand geschlossen sind. Die L\u00f6sung besteht darin, die Fu\u00dfleisten zu entfernen und die R\u00e4nder um weitere 1\/8\" abzuschneiden. Das ist eine m\u00fchsame Arbeit, und deshalb ist es so wichtig, es beim ersten Mal richtig zu machen.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Irrtum<\/th>\n<th style=\"text-align: left;\">Konsequenz<\/th>\n<th style=\"text-align: left;\">Pr\u00e4vention<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Verkeilen der Kanten<\/td>\n<td style=\"text-align: left;\">Blasenbildung\/Peaking<\/td>\n<td style=\"text-align: left;\">Bei der Installation Abstandshalter verwenden<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Kalte Installation<\/td>\n<td style=\"text-align: left;\">Knicken im Sommer<\/td>\n<td style=\"text-align: left;\">Zuerst HVAC auf 70\u00b0F einstellen<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Befestigung der Verkleidung am Boden<\/td>\n<td style=\"text-align: left;\">Gerissenes Gummi\/L\u00fccken<\/td>\n<td style=\"text-align: left;\">Verkleidung nur an die Wand nageln<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Keine Akklimatisierung<\/td>\n<td style=\"text-align: left;\">Schrumpfende N\u00e4hte<\/td>\n<td style=\"text-align: left;\">48 Stunden Ruhezeit<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Bei anspruchsvollen kommerziellen Projekten m\u00fcssen wir uns manchmal sogar noch mehr technische Daten ansehen.<\/p>\n<h2>Was sind die erweiterten technischen Spezifikationen f\u00fcr Profis?<\/h2>\n<p><strong>Professionelle Bauunternehmer sollten die Bewegung auf der Grundlage eines linearen Ausdehnungskoeffizienten von etwa $0,00013$ pro Grad Fahrenheit berechnen, insbesondere in L-f\u00f6rmigen R\u00e4umen, in denen sich die Spannung an \"Druckpunkten\" ansammelt.<\/strong><\/p>\n<p>When I consult on large-scale stadium projects, we look at the math. In a long hallway of 100 feet, a 20-degree temperature change can move the rubber by nearly 1\/4 inch across the total length. In L-shaped rooms, the &quot;inside corner&quot; of the L becomes a massive pressure point. If you don&#8217;t provide extra relief in those areas, the seams will eventually pull apart or the rubber will tear. We also look at the density. A $950 kg\/m\u00b3$ density roll will behave differently than a lighter, more porous mat.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Metrisch<\/th>\n<th style=\"text-align: left;\">Wert (typisch)<\/th>\n<th style=\"text-align: left;\">Bedeutung<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: left;\">Thermischer Ausdehnungskoeff.<\/td>\n<td style=\"text-align: left;\">$1.3 \\times 10^{-4} \/ ^\\circ F$<\/td>\n<td style=\"text-align: left;\">Vorhersage von Bewegungen<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Shore A H\u00e4rte<\/td>\n<td style=\"text-align: left;\">60 &#8211; 65<\/td>\n<td style=\"text-align: left;\">Widerstand gegen Kompression<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Typische Dichte<\/td>\n<td style=\"text-align: left;\">$900 &#8211; 1050 kg\/m^3$<\/td>\n<td style=\"text-align: left;\">Gewicht vs. Stabilit\u00e4t<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Identifizierung von Stresszonen<\/h3>\n<p>Bei komplexen Grundrissen sind die Ecken von S\u00e4ulen und die Enden langer Korridore die Stellen, an denen die meisten Bewegungen auftreten. Ich empfehle, die N\u00e4hte in diesen Bereichen doppelt zu schneiden, um eine perfekte Passform zu gew\u00e4hrleisten, die noch mikroskopische Verschiebungen im Material zul\u00e4sst.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-2-9.jpg&quot;\" alt=\"Diagramm der Belastungspunkte im Bodenbelag der Turnhalle\" \/><\/p>\n<p>Die Einhaltung dieser technischen Schritte gew\u00e4hrleistet ein erfolgreiches, professionelles Ergebnis.<\/p>\n<h2>Zusammenfassung der Checkliste f\u00fcr den Erfolg<\/h2>\n<ul>\n<li class=\"gfm-task-list\"><input type=\"checkbox\">48 Stunden lang in der tats\u00e4chlichen Installationsumgebung akklimatisiert?<\/li>\n<li class=\"gfm-task-list\"><input type=\"checkbox\">\u00dcberpr\u00fcfte Spaltgr\u00f6\u00dfe (1\/4\" f\u00fcr kleine R\u00e4ume, 3\/8\"+ f\u00fcr gro\u00dfe)?<\/li>\n<li class=\"gfm-task-list\"><input type=\"checkbox\">Abstandshalter aus Kunststoff, die an jeder Wand\/S\u00e4ule verwendet werden k\u00f6nnen?<\/li>\n<li class=\"gfm-task-list\"><input type=\"checkbox\">Wurde zur Abdeckung der L\u00fccke die richtige Verkleidung (Voutenboden oder \u00dcbergang) gew\u00e4hlt?<\/li>\n<\/ul>\n<h2>Schlussfolgerung<\/h2>\n<p>Richtige Dehnungsfugen sind die Versicherung f\u00fcr Ihre Investition in den Bodenbelag.<\/p>\n<hr \/>\n<p><strong>Wenn Sie ein gr\u00f6\u00dferes Projekt in einem Fitnessstudio planen oder technische Beratung zur Herstellung und Verlegung von Gummibodenbel\u00e4gen ben\u00f6tigen, k\u00f6nnen Sie mir eine private Nachricht schicken.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Standard rubber flooring installations require an expansion gap of 1\/4 inch to 3\/8 inch (6mm to 10mm) at all walls and fixed columns. This space allows the material to expand and contract naturally due to temperature and humidity changes without causing buckling or seam failure. I have spent years on job sites, and I can&#8230;<\/p>","protected":false},"author":4,"featured_media":8333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-8329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acoustic-underlay"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR<\/title>\n<meta name=\"description\" content=\"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meettfit.com\/de\/akustische-unterlage\/welche-dehnungsfuge-braucht-ein-gummibodenbelag-an-wanden-und-saulen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR\" \/>\n<meta property=\"og:description\" content=\"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meettfit.com\/de\/akustische-unterlage\/welche-dehnungsfuge-braucht-ein-gummibodenbelag-an-wanden-und-saulen\/\" \/>\n<meta property=\"og:site_name\" content=\"MF FLOOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100079773047357\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T09:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T03:07:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"1659230944@qq.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"1659230944@qq.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/\"},\"author\":{\"name\":\"1659230944@qq.com\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef\"},\"headline\":\"What Expansion Gap Does Rubber Flooring Need at Walls and Columns\",\"datePublished\":\"2026-04-21T09:00:45+00:00\",\"dateModified\":\"2026-04-22T03:07:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/\"},\"wordCount\":1815,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/meettfit.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg\",\"articleSection\":[\"Soundproof Flooring Solutions\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/\",\"url\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/\",\"name\":\"What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR\",\"isPartOf\":{\"@id\":\"https:\/\/meettfit.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg\",\"datePublished\":\"2026-04-21T09:00:45+00:00\",\"dateModified\":\"2026-04-22T03:07:39+00:00\",\"description\":\"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.\",\"breadcrumb\":{\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage\",\"url\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg\",\"contentUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg\",\"width\":800,\"height\":600,\"caption\":\"Rubber Flooring (4)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/meettfit.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What Expansion Gap Does Rubber Flooring Need at Walls and Columns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/meettfit.com\/#website\",\"url\":\"https:\/\/meettfit.com\/\",\"name\":\"MF FLOOR\",\"description\":\"fitness and sports floor China factory\",\"publisher\":{\"@id\":\"https:\/\/meettfit.com\/#organization\"},\"alternateName\":\"MF FLOOR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/meettfit.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/meettfit.com\/#organization\",\"name\":\"MF FLOOR\",\"alternateName\":\"MF FLOOR\",\"url\":\"https:\/\/meettfit.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png\",\"contentUrl\":\"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png\",\"width\":512,\"height\":512,\"caption\":\"MF FLOOR\"},\"image\":{\"@id\":\"https:\/\/meettfit.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100079773047357\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef\",\"name\":\"1659230944@qq.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/meettfit.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g\",\"caption\":\"1659230944@qq.com\"},\"url\":\"https:\/\/meettfit.com\/de\/author\/1659230944qq-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR","description":"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meettfit.com\/de\/akustische-unterlage\/welche-dehnungsfuge-braucht-ein-gummibodenbelag-an-wanden-und-saulen\/","og_locale":"de_DE","og_type":"article","og_title":"What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR","og_description":"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.","og_url":"https:\/\/meettfit.com\/de\/akustische-unterlage\/welche-dehnungsfuge-braucht-ein-gummibodenbelag-an-wanden-und-saulen\/","og_site_name":"MF FLOOR","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100079773047357","article_published_time":"2026-04-21T09:00:45+00:00","article_modified_time":"2026-04-22T03:07:39+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg","type":"image\/jpeg"}],"author":"1659230944@qq.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"1659230944@qq.com","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#article","isPartOf":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/"},"author":{"name":"1659230944@qq.com","@id":"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef"},"headline":"What Expansion Gap Does Rubber Flooring Need at Walls and Columns","datePublished":"2026-04-21T09:00:45+00:00","dateModified":"2026-04-22T03:07:39+00:00","mainEntityOfPage":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/"},"wordCount":1815,"commentCount":0,"publisher":{"@id":"https:\/\/meettfit.com\/#organization"},"image":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage"},"thumbnailUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg","articleSection":["Soundproof Flooring Solutions"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/","url":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/","name":"What Expansion Gap Does Rubber Flooring Need at Walls and Columns - MF FLOOR","isPartOf":{"@id":"https:\/\/meettfit.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage"},"image":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage"},"thumbnailUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg","datePublished":"2026-04-21T09:00:45+00:00","dateModified":"2026-04-22T03:07:39+00:00","description":"Learn why rubber flooring expands and how proper expansion gaps ensure long-term durability and prevent costly installation failures.","breadcrumb":{"@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#primaryimage","url":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg","contentUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2026\/04\/Rubber-Flooring-4-9.jpg","width":800,"height":600,"caption":"Rubber Flooring (4)"},{"@type":"BreadcrumbList","@id":"https:\/\/meettfit.com\/acoustic-underlay\/what-expansion-gap-does-rubber-flooring-need-at-walls-and-columns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/meettfit.com\/"},{"@type":"ListItem","position":2,"name":"What Expansion Gap Does Rubber Flooring Need at Walls and Columns"}]},{"@type":"WebSite","@id":"https:\/\/meettfit.com\/#website","url":"https:\/\/meettfit.com\/","name":"MF FLOOR","description":"fitness and sports floor China factory","publisher":{"@id":"https:\/\/meettfit.com\/#organization"},"alternateName":"MF FLOOR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meettfit.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/meettfit.com\/#organization","name":"MF FLOOR","alternateName":"MF FLOOR","url":"https:\/\/meettfit.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meettfit.com\/#\/schema\/logo\/image\/","url":"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png","contentUrl":"https:\/\/meettfit.com\/wp-content\/uploads\/2025\/02\/cropped-icon.png","width":512,"height":512,"caption":"MF FLOOR"},"image":{"@id":"https:\/\/meettfit.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100079773047357"]},{"@type":"Person","@id":"https:\/\/meettfit.com\/#\/schema\/person\/ba93f0ead95f571b725acc83f6544fef","name":"1659230944@qq.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/meettfit.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a00f8b283a4395bb3fdf16b29335b3a4?s=96&d=mm&r=g","caption":"1659230944@qq.com"},"url":"https:\/\/meettfit.com\/de\/author\/1659230944qq-com\/"}]}},"_links":{"self":[{"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/posts\/8329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/comments?post=8329"}],"version-history":[{"count":0,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/posts\/8329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/media\/8333"}],"wp:attachment":[{"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/media?parent=8329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/categories?post=8329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meettfit.com\/de\/wp-json\/wp\/v2\/tags?post=8329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}